{"id":4215,"date":"2014-02-12T17:42:49","date_gmt":"2014-02-12T19:42:49","guid":{"rendered":"http:\/\/escritacontabilidade.adv.br\/blog\/?p=4215"},"modified":"2014-02-12T17:42:49","modified_gmt":"2014-02-12T19:42:49","slug":"contabilidade-o-caminho-e-ajustar-receitas-e-gastos-a-realidade","status":"publish","type":"post","link":"https:\/\/escritacontabilidade.adv.br\/blog\/2014\/02\/contabilidade-o-caminho-e-ajustar-receitas-e-gastos-a-realidade\/","title":{"rendered":"Contabilidade: o caminho \u00e9 ajustar receitas e gastos \u00e0 realidade"},"content":{"rendered":"<p>A regra \u00e9 clara: no mesmo momento que realiza uma venda, a empresa contrai uma d\u00edvida tribut\u00e1ria porque parte do valor cobrado s\u00e3o impostos embutidos que devem ser recolhidos aos cofres p\u00fablicos.<br \/>\nApesar de conhec\u00ea-la, muitas empresas tem dificuldade de coloc\u00e1-la em pr\u00e1tica e registra o dinheiro dos impostos no fluxo de caixa como receita de vendas.<\/p>\n<p>Uma das dificuldades \u00e9 que quando deixa de fazer a segrega\u00e7\u00e3o e trata a parte do Governo como propriedade da empresa, acaba por se comprometer com gastos cujo valor supera aquele que de fato pertence a ela, o que distorce a realidade e causa v\u00e1rios problemas.<\/p>\n<p>O descuido com o assunto \u00e9 grande e ganha propor\u00e7\u00f5es que mesmo bons neg\u00f3cios acabam por fracassar por esse motivo. A vis\u00e3o distorcida da realidade leva a ado\u00e7\u00e3o de pr\u00e1ticas que fazem com que a solu\u00e7\u00e3o para os problemas fique cada vez mais dif\u00edcil de ser implementada.<\/p>\n<p>Muitas empresas, ao tentar fazer a segrega\u00e7\u00e3o, constatam que o n\u00edvel das receitas n\u00e3o s\u00e3o suficientes para cobrir o valor dos impostos, das despesas operacionais, dos custos de produ\u00e7\u00e3o e remunerar o propriet\u00e1rio &#8211; e que devido \u00e0 natureza n\u00e3o ser\u00e1 f\u00e1cil cortar os gastos em excesso.<\/p>\n<p>Uma das pr\u00e1ticas \u00e9 escolher os produtos que vende e definir os pre\u00e7os com base na concorr\u00eancia obtendo uma margem de lucro que acaba ficando muito aqu\u00e9m da necess\u00e1ria, o que leva \u00e0 falta de dinheiro no caixa da empresa.<\/p>\n<p>A falta da segrega\u00e7\u00e3o patrimonial entre pessoa jur\u00eddica e f\u00edsica \u00e9 outra pr\u00e1tica ruim, pois provoca a sa\u00edda de recursos que pertencem \u00e0 empresa para cobrir gastos pessoais do s\u00f3cio. Trata-se de dois exemplos de procedimentos que a administra\u00e7\u00e3o coloca em pr\u00e1tica por ter uma vis\u00e3o distorcida do caixa da empresa e tamb\u00e9m dos gastos que de fato s\u00e3o intrinsecamente ligados a atividade. Mudar esse tipo de pratica \u00e9 bem dif\u00edcil, exige muito esfor\u00e7o do propriet\u00e1rio e por isso muitos n\u00e3o conseguem mudar. Mudar procedimentos como esses exigem nova postura e ado\u00e7\u00e3o de novas pr\u00e1ticas.<\/p>\n<p>No caso do pre\u00e7o de vendas e escolha dos produtos para venda, algumas das alternativas s\u00e3o: o estudo do mercado procurando saber se est\u00e1 ou n\u00e3o saturado e por quanto tempo mais consumir\u00e1 o produto naquele pre\u00e7o; saber qual volume de vendas a empresa precisa atingir e se tem estrutura e processos eficientes para superar o ponto de equil\u00edbrio e gerar lucro; conhecer e calcular corretamente a carga tribut\u00e1ria que incide sobre o pre\u00e7o de vendas.<\/p>\n<p>Em rela\u00e7\u00e3o \u00e0 forma\u00e7\u00e3o de pre\u00e7o a pr\u00e1tica usual \u00e9 aplicar multiplicadores que entre outras coisas consideram a margem bruta de lucro e a carga tribut\u00e1ria que devem ser praticadas sobre o custo do produto.<\/p>\n<p>Cortar gastos \u00e9 sempre dif\u00edcil mais poss\u00edvel de se fazer. Normalmente s\u00e3o identificados custos fixos, aqueles que s\u00e3o recorrentes mas n\u00e3o guardam rela\u00e7\u00e3o direta com os produtos vendidos pela empresa. A t\u00edtulo de exemplo, instala\u00e7\u00f5es caras, mas subutilizadas ou inadequadas para o tipo de neg\u00f3cio da empresa; desperd\u00edcio de energia el\u00e9trica e m\u00e3o de obra.<\/p>\n<p>Encontrar o custo do produto correto n\u00e3o \u00e9 tarefa f\u00e1cil, por\u00e9m ao defini-lo \u00e9 poss\u00edvel cortar os custos em excesso, que s\u00e3o justamente aqueles que n\u00e3o s\u00e3o absorvidos pelos itens vendidos pela empresa.<\/p>\n<p>Al\u00e9m dos custos fixos, existem despesas decorrentes da falta de segrega\u00e7\u00e3o patrimonial. \u00c9 o gasto que o empres\u00e1rio tem mais dificuldades para cortar, pois significa alterar o padr\u00e3o de vida da fam\u00edlia. S\u00e3o gastos que n\u00e3o s\u00e3o previstos no or\u00e7amento, o que agrava ainda mais a situa\u00e7\u00e3o, j\u00e1 que o fato de existir dinheiro em caixa n\u00e3o significa a exist\u00eancia das condi\u00e7\u00f5es ideais para se incorrer em gastos que n\u00e3o est\u00e3o relacionados com o neg\u00f3cio da empresa. <\/p>\n<p>Eliminar as despesas pessoais do dono passa pela defini\u00e7\u00e3o de um valor fixo de retirada mensal que deve ser suficiente para atender suas necessidades pessoais. Regra essa que deve ser seguida fielmente pelo propriet\u00e1rio.<\/p>\n<p>Diante desses problemas de dif\u00edcil solu\u00e7\u00e3o, o empres\u00e1rio que se prop\u00f5e a enfrent\u00e1-los tem que estar disposto a agir de maneira diferente e tamb\u00e9m passar a fazer uso de ferramentas que n\u00e3o vinha utilizando.<\/p>\n<p>A contabilidade \u00e9 uma das ferramentas que pode ser bastante \u00fatil para auxili\u00e1-lo visto que seus registros possibilitam a elabora\u00e7\u00e3o dos relat\u00f3rios que v\u00e3o apresentar a ele muitas dessas informa\u00e7\u00f5es. Bem utilizadas elas servir\u00e3o para an\u00e1lise do que veio acontecendo na empresa e servir\u00e3o para todo o planejamento dos pr\u00f3ximos passos a serem seguidos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A regra \u00e9 clara: no mesmo momento que realiza uma venda, a empresa contrai uma d\u00edvida tribut\u00e1ria porque parte do valor cobrado s\u00e3o impostos embutidos que devem ser recolhidos aos cofres p\u00fablicos. Apesar de conhec\u00ea-la, muitas empresas tem dificuldade de coloc\u00e1-la em pr\u00e1tica e registra o dinheiro dos impostos no fluxo de caixa como receita [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[],"tags":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p28224-15Z","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6027,"url":"https:\/\/escritacontabilidade.adv.br\/blog\/2015\/11\/7-dicas-para-acabar-com-a-bagunca-nas-contas-do-seu-negocio\/","url_meta":{"origin":4215,"position":0},"title":"7 dicas para acabar com a bagun\u00e7a nas contas do seu neg\u00f3cio","author":"Clayton Teles das Merces","date":"25 novembro 2015","format":false,"excerpt":"Lidar com n\u00fameros costuma ser um desafio para empreendedores. Muitos criam o neg\u00f3cio a partir de uma ideia e, com a chegada da rotina, desesperam-se com a enxurrada de receitas e despesas. Essa dificuldade com as contas vem principalmente da falta de incentivo \u00e0 educa\u00e7\u00e3o financeira, afirma Rafael Mingone, s\u00f3cio-diretor\u2026","rel":"","context":"Em &quot;Contabilidade&quot;","block_context":{"text":"Contabilidade","link":"https:\/\/escritacontabilidade.adv.br\/blog\/Geral\/geral\/contabilidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4818,"url":"https:\/\/escritacontabilidade.adv.br\/blog\/2014\/07\/imposto-desanima-empresas\/","url_meta":{"origin":4215,"position":1},"title":"Imposto desanima empresas","author":"Clayton Teles das Merces","date":"7 julho 2014","format":false,"excerpt":"A carga tribut\u00e1ria brasileira, al\u00e9m de ser uma das mais pesadas do mundo, \u00e9 tamb\u00e9m uma das mais confusas. \u201cO empres\u00e1rio gasta em m\u00e9dia 2.400 horas com o contador para resolver toda a papelada com os impostos. Cerca de 80% dos pequenos empreendedores aqui da capital t\u00eam dificuldade em calcular\u2026","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4477,"url":"https:\/\/escritacontabilidade.adv.br\/blog\/2014\/04\/receita-aperta-cerco-contra-fraudes-na-declaracao-do-ir\/","url_meta":{"origin":4215,"position":2},"title":"Receita aperta cerco contra fraudes na declara\u00e7\u00e3o do IR","author":"Clayton Teles das Merces","date":"17 abril 2014","format":false,"excerpt":"A 14 dias do prazo final de entrega das declara\u00e7\u00f5es do Imposto de Renda, a Receita Federal est\u00e1 mais atenta contra tentativas de fraudes. Duas opera\u00e7\u00f5es deflagradas pelo Fisco \u2014 na Bahia e no Paran\u00e1 \u2014 refor\u00e7am que o \u00f3rg\u00e3o se mant\u00e9m na cola de esquemas que visam burlar o\u2026","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4951,"url":"https:\/\/escritacontabilidade.adv.br\/blog\/2014\/08\/asun-e-alvo-de-operacao-da-receita-federal\/","url_meta":{"origin":4215,"position":3},"title":"Asun \u00e9 alvo de opera\u00e7\u00e3o da Receita Federal","author":"Clayton Teles das Merces","date":"15 agosto 2014","format":false,"excerpt":"Uma opera\u00e7\u00e3o conjunta foi deflagrada na manh\u00e3 de ontem, em Gravata\u00ed, pela Receita Federal e a Pol\u00edcia Federal, para investigar a origem das movimenta\u00e7\u00f5es financeiras da rede de supermercados Asun. A empresa possui d\u00e9bitos fiscais declarados na ordem de R$ 260 milh\u00f5es, mas o fisco encontra dificuldades para ajustar o\u2026","rel":"","context":"Post similar","block_context":{"text":"Post similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5818,"url":"https:\/\/escritacontabilidade.adv.br\/blog\/2015\/07\/12-erros-que-acabam-com-as-contas-do-seu-negocio\/","url_meta":{"origin":4215,"position":4},"title":"12 erros que acabam com as contas do seu neg\u00f3cio","author":"Clayton Teles das Merces","date":"14 julho 2015","format":false,"excerpt":"Olhar as contas do neg\u00f3cio nem sempre \u00e9 uma tarefa f\u00e1cil, seja por quest\u00f5es econ\u00f4micas ou emocionais. Mas ignor\u00e1-las pode gerar um estresse ainda maior: o da fal\u00eancia. Para Marcelo Correa, professor do curso de Administra\u00e7\u00e3o da Universidade Anhembi Morumbi, devemos nos comportar mais como \"formigas\"\u00a0 e menos como \"cigarras\"\u2026","rel":"","context":"Em &quot;Contabilidade&quot;","block_context":{"text":"Contabilidade","link":"https:\/\/escritacontabilidade.adv.br\/blog\/Geral\/geral\/contabilidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5669,"url":"https:\/\/escritacontabilidade.adv.br\/blog\/2015\/04\/os-cruzamentos-de-informacoes-do-imposto-de-renda-que-te-levam-a-malha-fina\/","url_meta":{"origin":4215,"position":5},"title":"Os Cruzamentos de Informa\u00e7\u00f5es do Imposto de Renda que te levam \u00e0 malha fina","author":"Clayton Teles das Merces","date":"28 abril 2015","format":false,"excerpt":"Para n\u00e3o cair na malha fina, o contribuinte que est\u00e1 obrigado a declarar o Imposto de Renda (IR) 2015 precisa ter aten\u00e7\u00e3o redobrada ao preencher alguns itens da declara\u00e7\u00e3o de IR que revelam ao Fisco eventuais omiss\u00f5es ou inconsist\u00eancias. A lista de dedos-duros s\u00f3 vem aumentando porque a cada ano\u2026","rel":"","context":"Em &quot;Contabilidade&quot;","block_context":{"text":"Contabilidade","link":"https:\/\/escritacontabilidade.adv.br\/blog\/Geral\/geral\/contabilidade\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/posts\/4215"}],"collection":[{"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/comments?post=4215"}],"version-history":[{"count":1,"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/posts\/4215\/revisions"}],"predecessor-version":[{"id":4216,"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/posts\/4215\/revisions\/4216"}],"wp:attachment":[{"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/media?parent=4215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/categories?post=4215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escritacontabilidade.adv.br\/blog\/wp-json\/wp\/v2\/tags?post=4215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}